{"id":14701,"date":"2025-10-15T17:44:09","date_gmt":"2025-10-15T17:44:09","guid":{"rendered":"https:\/\/cheesecakelabs.com\/blog\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/"},"modified":"2026-08-15T06:59:26","modified_gmt":"2026-08-15T06:59:26","slug":"cheesecake-labs-via-labs-interoperabilidade-blockchain","status":"publish","type":"post","link":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/","title":{"rendered":"Cheesecake Labs e VIA Labs: interoperabilidade real entre Stellar, Cardano e redes EVM"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Construindo a base para uma Web3 conectada e interoper\u00e1vel<\/strong><\/h3>\n\n\n\n<p>Temos o prazer de anunciar nossa parceria com a <a href=\"https:\/\/vialabs.io\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>VIA Labs<\/strong><\/a>, empresa de infraestrutura Web3 em crescimento acelerado que est\u00e1 redefinindo como dados, tokens e NFTs circulam entre blockchains.<\/p>\n\n\n\n<p>A vis\u00e3o da VIA Labs \u00e9 tornar a comunica\u00e7\u00e3o entre ecossistemas blockchain algo direto, sem atrito. A infraestrutura de mensageria cross-chain da empresa j\u00e1 conecta mais de 140 redes, entre blockchains EVM e n\u00e3o EVM, como <a href=\"https:\/\/cheesecakelabs.com\/blog\/rede-stellar-como-funciona\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stellar<\/a> e <a href=\"https:\/\/cheesecakelabs.com\/blog\/desenvolvimento-blockchain-cardano\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cardano<\/a>. Junto com eles, estamos construindo a base para uma interoperabilidade segura, escal\u00e1vel e fluida entre ecossistemas blockchain.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conectando um cen\u00e1rio blockchain fragmentado<\/strong><\/h2>\n\n\n\n<p>A fragmenta\u00e7\u00e3o continua sendo um dos maiores desafios da Web3. Cada blockchain opera com regras, modelos de programa\u00e7\u00e3o e sistemas de transa\u00e7\u00e3o pr\u00f3prios.<\/p>\n\n\n\n<p>A infraestrutura de mensageria da VIA Labs funciona como uma camada universal de tradu\u00e7\u00e3o: o desenvolvedor constr\u00f3i e conecta em v\u00e1rios ecossistemas sem precisar administrar a complexidade de cada rede.<\/p>\n\n\n\n<p>Para viabilizar isso, a VIA Labs se uniu \u00e0 <a href=\"https:\/\/cheesecakelabs.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cheesecake Labs<\/a> pela nossa experi\u00eancia em <a href=\"https:\/\/cheesecakelabs.com\/services\/blockchain\/\" target=\"_blank\" rel=\"noreferrer noopener\">arquitetura, seguran\u00e7a e desenvolvimento blockchain<\/a>, alinhando tecnologia e estrat\u00e9gia para garantir interoperabilidade fluida tanto para quem desenvolve quanto para quem usa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ampliando a interoperabilidade: a Stellar entra na rede<\/strong><\/h2>\n\n\n\n<p>O avan\u00e7o da VIA Labs em inova\u00e7\u00e3o cross-chain foi reconhecido recentemente <a href=\"https:\/\/communityfund.stellar.org\/project\/via-labs-a1k\" target=\"_blank\" rel=\"noreferrer noopener\">pelo Stellar Community Fund, que concedeu ao projeto um grant de US$ 95.000<\/a> por levar adiante a interoperabilidade entre a <a href=\"https:\/\/stellar.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stellar<\/a> e outros ecossistemas blockchain.<\/p>\n\n\n\n<p>Para trazer a Stellar para a rede, a VIA Labs trabalha com a Cheesecake Labs no desenho e na implementa\u00e7\u00e3o de uma integra\u00e7\u00e3o nativa e segura, que conecta a Stellar a ambientes baseados em EVM. Com isso, tokens, mensagens e ativos digitais circulam entre os dois ecossistemas sem perder consist\u00eancia, confiabilidade e simplicidade para quem desenvolve.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Privacidade entre chains: a integra\u00e7\u00e3o VIA Labs x Midnight<\/strong><\/h2>\n\n\n\n<p>Interoperabilidade \u00e9 s\u00f3 parte da hist\u00f3ria. A VIA Labs tamb\u00e9m avan\u00e7a em privacidade no blockchain com a <a href=\"https:\/\/midnight.network\/\" target=\"_blank\" rel=\"noreferrer noopener\">Midnight<\/a>, a nova rede da <a href=\"https:\/\/cardano.org\/\">Cardano<\/a> voltada para privacidade.<\/p>\n\n\n\n<p>Constru\u00edda sobre criptografia zero-knowledge, a Midnight permite proteger os dados do usu\u00e1rio sem abrir m\u00e3o de conformidade regulat\u00f3ria. Com o suporte de engenharia da Cheesecake Labs, a camada de privacidade da Midnight ser\u00e1 conectada em breve \u00e0 infraestrutura da VIA Labs, habilitando comunica\u00e7\u00e3o segura e com preserva\u00e7\u00e3o de privacidade em mais de 140 blockchains.<\/p>\n\n\n\n<p>Essa integra\u00e7\u00e3o d\u00e1 aos desenvolvedores a base para criar aplica\u00e7\u00f5es interoper\u00e1veis e com dados protegidos, que equilibram descentraliza\u00e7\u00e3o, privacidade e conformidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Feito para escalar, desenhado para quem desenvolve<\/strong><\/h2>\n\n\n\n<p>Nosso trabalho com a VIA Labs seguiu os mesmos princ\u00edpios que orientam toda parceria da Cheesecake Labs:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Escal\u00e1vel por design: <\/strong>m\u00f3dulos reutiliz\u00e1veis que tornam mais r\u00e1pida a integra\u00e7\u00e3o de novos blockchains.<\/li>\n\n\n\n<li><strong>Seguro na base:<\/strong> padr\u00f5es criptogr\u00e1ficos fortes, da gest\u00e3o de chaves \u00e0 valida\u00e7\u00e3o de transa\u00e7\u00f5es.<\/li>\n\n\n\n<li><strong>Experi\u00eancia developer-first: <\/strong>SDKs e APIs unificados que simplificam o desenvolvimento e a integra\u00e7\u00e3o cross-chain.<\/li>\n<\/ol>\n\n\n\n<p>Essas escolhas de design colocam a VIA Labs n\u00e3o como mais um protocolo Web3, e sim como uma camada de infraestrutura central para a pr\u00f3xima gera\u00e7\u00e3o de aplica\u00e7\u00f5es descentralizadas.<\/p>\n\n\n\n<p><em>\u201cTrabalhar ao lado da Cheesecake Labs foi fluido do onboarding \u00e0 entrega. O time \u00e9 profissional, curioso e muito adapt\u00e1vel, sempre r\u00e1pido para atender \u00e0s nossas necessidades cross-chain, mesmo quando os alvos mudam no meio do caminho. Eles se tornaram uma extens\u00e3o da nossa pr\u00f3pria cultura de engenharia na VIA Labs.\u201d<\/em><\/p>\n\n\n\n<p><em>Robert (Cletus) Pilat, COO da VIA Labs<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O futuro de uma Web3 interoper\u00e1vel<\/strong><\/h2>\n\n\n\n<p>A colabora\u00e7\u00e3o Cheesecake Labs x VIA Labs \u00e9 um passo importante rumo a um ecossistema Web3 mais conectado e mais amig\u00e1vel para quem desenvolve.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para os desenvolvedores, simplifica a cria\u00e7\u00e3o de aplica\u00e7\u00f5es cross-chain.<\/li>\n\n\n\n<li>Para as empresas, entrega escalabilidade e confian\u00e7a regulat\u00f3ria.<\/li>\n\n\n\n<li>Para o ecossistema, acelera a virada para uma interoperabilidade segura e com privacidade em primeiro lugar.<\/li>\n<\/ul>\n\n\n\n<p>Conforme a VIA Labs expande seu protocolo omni-chain para novos blockchains e redes de privacidade, a Cheesecake Labs segue como parceira de engenharia dedicada, construindo a base para a pr\u00f3xima fase de inova\u00e7\u00e3o em Web3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O que vem pela frente<\/strong><\/h2>\n\n\n\n<p>Essa parceria \u00e9 s\u00f3 o come\u00e7o. Junto com a VIA Labs, vamos continuar avan\u00e7ando em padr\u00f5es cross-chain, integrando novas redes Layer-2 e explorando tecnologias de privacidade que tornam a Web3 mais aberta, segura e centrada no usu\u00e1rio.<\/p>\n\n\n\n<p>Na Cheesecake Labs, temos orgulho de fazer parte dessa jornada, combinando pensamento estrat\u00e9gico, excel\u00eancia t\u00e9cnica e colabora\u00e7\u00e3o para ajudar a moldar o futuro da infraestrutura descentralizada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construindo a base para uma Web3 conectada e interoper\u00e1vel Temos o prazer de anunciar nossa parceria com a VIA Labs, empresa de infraestrutura Web3 em crescimento acelerado que est\u00e1 redefinindo como dados, tokens e NFTs circulam entre blockchains. A vis\u00e3o da VIA Labs \u00e9 tornar a comunica\u00e7\u00e3o entre ecossistemas blockchain algo direto, sem atrito. A [&hellip;]<\/p>\n","protected":false},"author":92,"featured_media":13068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Cheesecake Labs e VIA Labs: interoperabilidade blockchain","_yoast_wpseo_metadesc":"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.","_yoast_wpseo_meta-robots-noindex":"","_yoast_wpseo_canonical":"","footnotes":"","ckl_wpml_lang":"br","ckl_wpml_source_id":13061,"ckl_wpml_status":"ok: lang=br trid=54732 source=13061 at 2026-08-14 22:22:29"},"categories":[1328,1166,1165],"tags":[],"class_list":["post-14701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-blockchain-br","category-blockchain"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cheesecake Labs e VIA Labs: interoperabilidade blockchain<\/title>\n<meta name=\"description\" content=\"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cheesecake Labs e VIA Labs: interoperabilidade blockchain\" \/>\n<meta property=\"og:description\" content=\"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\" \/>\n<meta property=\"og:site_name\" content=\"Cheesecake Labs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cheesecakelabs\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T17:44:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-15T06:59:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"861\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cheesecake Labs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cheesecakelabs\" \/>\n<meta name=\"twitter:site\" content=\"@cheesecakelabs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\"},\"author\":{\"name\":\"Diana Martins\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#\/schema\/person\/37fa2f0fa5f8d3cbaeb21b973fa5c4b9\"},\"headline\":\"Cheesecake Labs e VIA Labs: interoperabilidade real entre Stellar, Cardano e redes EVM\",\"datePublished\":\"2025-10-15T17:44:09+00:00\",\"dateModified\":\"2026-08-15T06:59:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\"},\"wordCount\":791,\"publisher\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg\",\"articleSection\":[\"News\",\"Blockchain\",\"Blockchain\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\",\"url\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\",\"name\":\"Cheesecake Labs e VIA Labs: interoperabilidade blockchain\",\"isPartOf\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg\",\"datePublished\":\"2025-10-15T17:44:09+00:00\",\"dateModified\":\"2026-08-15T06:59:26+00:00\",\"description\":\"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.\",\"breadcrumb\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage\",\"url\":\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg\",\"contentUrl\":\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg\",\"width\":1920,\"height\":861,\"caption\":\"via labs and cheesecake labs partnership\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cheesecakelabs.com\/blog\/br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cheesecake Labs e VIA Labs: interoperabilidade real entre Stellar, Cardano e redes EVM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#website\",\"url\":\"https:\/\/cheesecakelabs.com\/blog\/br\/\",\"name\":\"Cheesecake Labs\",\"description\":\"Empresa de desenvolvimento e design de aplicativos mobile &amp; web que est\u00e1 reinventando o desenvolvimento de produtos com times remotos. N\u00f3s desenvolvemos aplicativos iOS, Android e aplica\u00e7\u00f5es Web com as melhores empresas dos EUA, do Brasil e do mundo.\",\"publisher\":{\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cheesecakelabs.com\/blog\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#organization\",\"name\":\"Cheesecake Labs\",\"alternateName\":\"Cheesecake Labs Inc\",\"url\":\"https:\/\/cheesecakelabs.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/cheesecakelabs.com\/#logo\",\"url\":\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2022\/06\/cheesecake-labs-1.png\",\"contentUrl\":\"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2022\/06\/cheesecake-labs-1.png\",\"caption\":\"Cheesecake Labs\",\"inLanguage\":\"br\"},\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/cheesecakelabs.com\/#primary-image\",\"url\":\"https:\/\/ckl-website-v4-strapi-prod.s3.us-east-2.amazonaws.com\/ai_software_development_company_83fb512983.webp\",\"contentUrl\":\"https:\/\/ckl-website-v4-strapi-prod.s3.us-east-2.amazonaws.com\/ai_software_development_company_83fb512983.webp\",\"width\":1920,\"height\":1080,\"caption\":\"Cheesecake Labs \u2014 AI, Data & Blockchain software development services\",\"inLanguage\":\"br\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cheesecakelabs\",\"https:\/\/x.com\/cheesecakelabs\",\"https:\/\/www.instagram.com\/cheesecakelabs\/\",\"https:\/\/www.linkedin.com\/company\/cheesecake-labs\/\",\"https:\/\/www.youtube.com\/channel\/UCdGEQ5AHJcmIlaOaI5fGGVA\",\"https:\/\/clutch.co\/profile\/cheesecake-labs\",\"https:\/\/www.behance.net\/cheesecakelabs\",\"https:\/\/dribbble.com\/cheesecakelabs\",\"https:\/\/www.designrush.com\/agency\/profile\/cheesecake-labs\",\"https:\/\/www.g2.com\/products\/cheesecake-labs\/reviews\"],\"description\":\"Cheesecake Labs is a software development studio that designs and builds custom digital products \u2014 web, mobile, and platforms \u2014 combining product design and high-performance engineering.\",\"foundingDate\":\"2013\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#\/schema\/person\/37fa2f0fa5f8d3cbaeb21b973fa5c4b9\",\"name\":\"Diana Martins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cheesecakelabs.com\/blog\/br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d074fb633a22723051c9d98ffc13065a28f0b52bd30a4c0a832ee19820caa4ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d074fb633a22723051c9d98ffc13065a28f0b52bd30a4c0a832ee19820caa4ba?s=96&d=mm&r=g\",\"caption\":\"Diana Martins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cheesecake Labs e VIA Labs: interoperabilidade blockchain","description":"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/","og_locale":"pt_BR","og_type":"article","og_title":"Cheesecake Labs e VIA Labs: interoperabilidade blockchain","og_description":"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.","og_url":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/","og_site_name":"Cheesecake Labs","article_publisher":"https:\/\/www.facebook.com\/cheesecakelabs","article_published_time":"2025-10-15T17:44:09+00:00","article_modified_time":"2026-08-15T06:59:26+00:00","og_image":[{"width":1920,"height":861,"url":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg","type":"image\/jpeg"}],"author":"Cheesecake Labs","twitter_card":"summary_large_image","twitter_creator":"@cheesecakelabs","twitter_site":"@cheesecakelabs","twitter_misc":{"Escrito por":null,"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#article","isPartOf":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/"},"author":{"name":"Diana Martins","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#\/schema\/person\/37fa2f0fa5f8d3cbaeb21b973fa5c4b9"},"headline":"Cheesecake Labs e VIA Labs: interoperabilidade real entre Stellar, Cardano e redes EVM","datePublished":"2025-10-15T17:44:09+00:00","dateModified":"2026-08-15T06:59:26+00:00","mainEntityOfPage":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/"},"wordCount":791,"publisher":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#organization"},"image":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage"},"thumbnailUrl":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg","articleSection":["News","Blockchain","Blockchain"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/","url":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/","name":"Cheesecake Labs e VIA Labs: interoperabilidade blockchain","isPartOf":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage"},"image":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage"},"thumbnailUrl":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg","datePublished":"2025-10-15T17:44:09+00:00","dateModified":"2026-08-15T06:59:26+00:00","description":"A parceria com a VIA Labs traz interoperabilidade blockchain real entre Stellar, Cardano e redes EVM, al\u00e9m de privacidade entre chains.","breadcrumb":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#primaryimage","url":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg","contentUrl":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2025\/10\/via-labs-x-cheesecake-labspng.jpg","width":1920,"height":861,"caption":"via labs and cheesecake labs partnership"},{"@type":"BreadcrumbList","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/cheesecake-labs-via-labs-interoperabilidade-blockchain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cheesecakelabs.com\/blog\/br\/blog\/"},{"@type":"ListItem","position":2,"name":"Cheesecake Labs e VIA Labs: interoperabilidade real entre Stellar, Cardano e redes EVM"}]},{"@type":"WebSite","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#website","url":"https:\/\/cheesecakelabs.com\/blog\/br\/","name":"Cheesecake Labs","description":"Empresa de desenvolvimento e design de aplicativos mobile &amp; web que est\u00e1 reinventando o desenvolvimento de produtos com times remotos. N\u00f3s desenvolvemos aplicativos iOS, Android e aplica\u00e7\u00f5es Web com as melhores empresas dos EUA, do Brasil e do mundo.","publisher":{"@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cheesecakelabs.com\/blog\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#organization","name":"Cheesecake Labs","alternateName":"Cheesecake Labs Inc","url":"https:\/\/cheesecakelabs.com\/","logo":{"@type":"ImageObject","@id":"https:\/\/cheesecakelabs.com\/#logo","url":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2022\/06\/cheesecake-labs-1.png","contentUrl":"https:\/\/ckl-website-static.s3.amazonaws.com\/wp-content\/uploads\/2022\/06\/cheesecake-labs-1.png","caption":"Cheesecake Labs","inLanguage":"br"},"image":{"@type":"ImageObject","@id":"https:\/\/cheesecakelabs.com\/#primary-image","url":"https:\/\/ckl-website-v4-strapi-prod.s3.us-east-2.amazonaws.com\/ai_software_development_company_83fb512983.webp","contentUrl":"https:\/\/ckl-website-v4-strapi-prod.s3.us-east-2.amazonaws.com\/ai_software_development_company_83fb512983.webp","width":1920,"height":1080,"caption":"Cheesecake Labs \u2014 AI, Data & Blockchain software development services","inLanguage":"br"},"sameAs":["https:\/\/www.facebook.com\/cheesecakelabs","https:\/\/x.com\/cheesecakelabs","https:\/\/www.instagram.com\/cheesecakelabs\/","https:\/\/www.linkedin.com\/company\/cheesecake-labs\/","https:\/\/www.youtube.com\/channel\/UCdGEQ5AHJcmIlaOaI5fGGVA","https:\/\/clutch.co\/profile\/cheesecake-labs","https:\/\/www.behance.net\/cheesecakelabs","https:\/\/dribbble.com\/cheesecakelabs","https:\/\/www.designrush.com\/agency\/profile\/cheesecake-labs","https:\/\/www.g2.com\/products\/cheesecake-labs\/reviews"],"description":"Cheesecake Labs is a software development studio that designs and builds custom digital products \u2014 web, mobile, and platforms \u2014 combining product design and high-performance engineering.","foundingDate":"2013"},{"@type":"Person","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#\/schema\/person\/37fa2f0fa5f8d3cbaeb21b973fa5c4b9","name":"Diana Martins","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cheesecakelabs.com\/blog\/br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d074fb633a22723051c9d98ffc13065a28f0b52bd30a4c0a832ee19820caa4ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d074fb633a22723051c9d98ffc13065a28f0b52bd30a4c0a832ee19820caa4ba?s=96&d=mm&r=g","caption":"Diana Martins"}}]}},"_links":{"self":[{"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/posts\/14701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/comments?post=14701"}],"version-history":[{"count":2,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/posts\/14701\/revisions"}],"predecessor-version":[{"id":14957,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/posts\/14701\/revisions\/14957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/media\/13068"}],"wp:attachment":[{"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/media?parent=14701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/categories?post=14701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cheesecakelabs.com\/blog\/br\/wp-json\/wp\/v2\/tags?post=14701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}